{"id":95716,"date":"2026-04-21T14:01:25","date_gmt":"2026-04-21T12:01:25","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/h-020-lc3b-honda-hornet-600-2003-2006\/"},"modified":"2026-04-21T14:01:25","modified_gmt":"2026-04-21T12:01:25","slug":"h-020-lc3b-honda-hornet-600-2003-2006","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/fr\/product\/h-020-lc3b-honda-hornet-600-2003-2006\/","title":{"rendered":"H.020.LC3B &#8211; Honda HORNET 600 2003 > 2006"},"content":{"rendered":"<p>R\u00e9alis\u00e9 pour am\u00e9liorer <strong>l\u2019aspect, le son et les prestations<\/strong> de la moto, le pot slip-on Mivv est issu de l\u2019attention maximale vers le design, en vue de satisfaire ceux qui souhaitent se <strong>d\u00e9marquer<\/strong> aussi par l\u2019allure de leur moto.<\/p>\n<p>Le pot X-CONE est destin\u00e9 aux motos sportives et n\u00e9o &#8211; r\u00e9tro. Ce silencieux de la forme <strong>conique<\/strong> est caract\u00e9ris\u00e9 par un grand soin des d\u00e9tails.<\/p>\n<p>R\u00e9alis\u00e9 en acier inox avec finition <strong>\u2018black moon\u2019<\/strong> obtenue gr\u00e2ce \u00e0 une sp\u00e9ciale peinture \u00e0 base c\u00e9ramique qui donne au produit un <strong>aspect<\/strong> plus <strong>agressif<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e9alis\u00e9 pour am\u00e9liorer l\u2019aspect, le son et les prestations de la moto, le pot slip-on Mivv est issu de l\u2019attention maximale vers le design, en vue de satisfaire ceux qui souhaitent se d\u00e9marquer aussi par l\u2019allure de leur moto. Le pot X-CONE est destin\u00e9 aux motos sportives et n\u00e9o &#8211; r\u00e9tro. Ce silencieux de la [&hellip;]<\/p>\n","protected":false},"featured_media":64012,"template":"","meta":{"_acf_changed":false},"product_brand":[24525,23846,24504],"product_cat":[704],"product_tag":[],"class_list":{"0":"post-95716","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2003-2006-hornet-600","7":"product_brand-honda","8":"product_brand-hornet-600","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product\/95716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/media\/64012"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/media?parent=95716"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_brand?post=95716"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_cat?post=95716"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_tag?post=95716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}