{"id":96640,"date":"2026-04-21T14:08:29","date_gmt":"2026-04-21T12:08:29","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/e-005-lm3b-benelli-502c-2019-2024\/"},"modified":"2026-04-21T14:08:29","modified_gmt":"2026-04-21T12:08:29","slug":"e-005-lm3b-benelli-502c-2019-2024","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/fr\/product\/e-005-lm3b-benelli-502c-2019-2024\/","title":{"rendered":"E.005.LM3B \u2013 BENELLI 502C 2019 > 2024"},"content":{"rendered":"<p>R\u00e9alis\u00e9 pour am\u00e9liorer <strong>l\u2019aspect, le son et les prestations<\/strong> de la moto, le pot slip-on Mivv est issu de l\u2019attention maximale vers le design, en vue de satisfaire ceux qui souhaitent se <strong>d\u00e9marquer<\/strong> aussi par l\u2019allure de leur moto.<\/p>\n<p>Le pot <strong>MK3<\/strong>, fruit de l&rsquo;exp\u00e9rience acquise lors des championnats du monde <strong>Moto3 et Moto2<\/strong>, est la synth\u00e8se parfaite entre <strong>performance et technologie<\/strong>. Avec un <strong>design<\/strong> similaire aux \u00e9chappements con\u00e7us pour le <strong>championnat mondial Moto3<\/strong>, le MK3 est un produit <strong>compact<\/strong> capable de lib\u00e9rer <strong>le son captivant MIVV<\/strong>. <\/p>\n<p>La version Black se caract\u00e9rise par un corps central en acier inox 304 noir avec finition\u00a0<strong>\u2018Black Moon\u2019<\/strong>\u00a0obtenue gr\u00e2ce \u00e0 une sp\u00e9ciale peinture c\u00e9ramique qui, conjointement \u00e0 la grille de protection sur l\u2019embout de sortie, donne au silencieux un look plus <strong>agressif<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e9alis\u00e9 pour am\u00e9liorer l\u2019aspect, le son et les prestations de la moto, le pot slip-on Mivv est issu de l\u2019attention maximale vers le design, en vue de satisfaire ceux qui souhaitent se d\u00e9marquer aussi par l\u2019allure de leur moto. Le pot MK3, fruit de l&rsquo;exp\u00e9rience acquise lors des championnats du monde Moto3 et Moto2, est [&hellip;]<\/p>\n","protected":false},"featured_media":64218,"template":"","meta":{"_acf_changed":false},"product_brand":[21928,21921,21915],"product_cat":[704],"product_tag":[],"class_list":{"0":"post-96640","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2019-502-c","7":"product_brand-502-c","8":"product_brand-benelli","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product\/96640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/media\/64218"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/media?parent=96640"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_brand?post=96640"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_cat?post=96640"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_tag?post=96640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}