{"id":97501,"date":"2026-04-21T14:15:53","date_gmt":"2026-04-21T12:15:53","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/b-038-l6p-bmw-f-900-r-2020-2024\/"},"modified":"2026-04-21T14:15:53","modified_gmt":"2026-04-21T12:15:53","slug":"b-038-l6p-bmw-f-900-r-2020-2024","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/fr\/product\/b-038-l6p-bmw-f-900-r-2020-2024\/","title":{"rendered":"B.038.L6P \u2013 BMW F 900 R 2020 > 2024"},"content":{"rendered":"<p>R\u00e9alis\u00e9 pour am\u00e9liorer <strong>l\u2019aspect, le son et les prestations<\/strong> de la moto, le pot slip-on Mivv est issu de l\u2019attention maximale vers le design, en vue de satisfaire ceux qui souhaitent se <strong>d\u00e9marquer<\/strong> aussi par l\u2019allure de leur moto.<\/p>\n<p>Le pot GP PRO montre avec fiert\u00e9 les <strong>soudures TIG semi-artisanales<\/strong>, le <strong>design compact<\/strong> et le <strong>son profond<\/strong>. Inspir\u00e9 au monde des <strong>comp\u00e9titions<\/strong>, la sortie du pot est \u00e9quip\u00e9 d\u2019une <strong>grille de protection amovible<\/strong> qui cache le dB-killer. Sur le silencieux, tr\u00e8s \u00e9vident, le logo Mivv par laser.<\/p>\n<p>Le corps en <strong>titane<\/strong> bross\u00e9 a l\u2019aspect <strong>\u201cperl\u00e9\u201d<\/strong>, obtenu par un traitement sp\u00e9cial lui donnant une allure inimitable. C\u2019est la <strong>choix du VIP.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>HOMOLOGUE EURO 5. Compatible uniquement avec les sacoches d&rsquo;origine<\/p>\n","protected":false},"featured_media":7783,"template":"","meta":{"_acf_changed":false},"product_brand":[22243,22103,22236],"product_cat":[704],"product_tag":[],"class_list":{"0":"post-97501","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2020-f-900-r","7":"product_brand-bmw","8":"product_brand-f-900-r","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product\/97501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/media\/7783"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/media?parent=97501"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_brand?post=97501"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_cat?post=97501"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_tag?post=97501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}