{"id":99769,"date":"2026-04-21T14:34:32","date_gmt":"2026-04-21T12:34:32","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/h-083-l2p-honda-cbr-500-r-2019-2020\/"},"modified":"2026-04-21T14:34:32","modified_gmt":"2026-04-21T12:34:32","slug":"h-083-l2p-honda-cbr-500-r-2019-2020","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/fr\/product\/h-083-l2p-honda-cbr-500-r-2019-2020\/","title":{"rendered":"H.083.L2P &#8211; HONDA CBR 500 R 2019 > 2020"},"content":{"rendered":"<p>R\u00e9alis\u00e9 pour am\u00e9liorer <strong>l\u2019aspect, le son et les prestations<\/strong> de la moto, le pot slip-on Mivv est issu de l\u2019attention maximale vers le design, en vue de satisfaire ceux qui souhaitent se <strong>d\u00e9marquer<\/strong> aussi par l\u2019allure de leur moto.<\/p>\n<p>Le pot GP PRO montre avec fiert\u00e9 les <strong>soudures TIG semi-artisanales<\/strong>, le <strong>design compact<\/strong> et le <strong>son profond<\/strong>. Inspir\u00e9 au monde des <strong>comp\u00e9titions<\/strong>, la sortie du pot est \u00e9quip\u00e9 d\u2019une <strong>grille de protection amovible<\/strong> qui cache le dB-killer. Sur le silencieux, tr\u00e8s \u00e9vident, le logo Mivv par laser.<\/p>\n<p>Le corps en <strong>carbone poli<\/strong>. C\u2019est la choix de qui pr\u00e9tend <strong>look et technologie au top au m\u00eame temps.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e9alis\u00e9 pour am\u00e9liorer l\u2019aspect, le son et les prestations de la moto, le pot slip-on Mivv est issu de l\u2019attention maximale vers le design, en vue de satisfaire ceux qui souhaitent se d\u00e9marquer aussi par l\u2019allure de leur moto. Le pot GP PRO montre avec fiert\u00e9 les soudures TIG semi-artisanales, le design compact et le [&hellip;]<\/p>\n","protected":false},"featured_media":63702,"template":"","meta":{"_acf_changed":false},"product_brand":[24182,24168,23846],"product_cat":[704],"product_tag":[],"class_list":{"0":"post-99769","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2019-2020-cbr-500-r","7":"product_brand-cbr-500-r","8":"product_brand-honda","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product\/99769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/media\/63702"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/media?parent=99769"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_brand?post=99769"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_cat?post=99769"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_tag?post=99769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}