{"id":100262,"date":"2026-04-21T14:38:57","date_gmt":"2026-04-21T12:38:57","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/h-085-l2p-honda-cb-750-hornet-2023-2024\/"},"modified":"2026-04-21T14:38:57","modified_gmt":"2026-04-21T12:38:57","slug":"h-085-l2p-honda-cb-750-hornet-2023-2024","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/h-085-l2p-honda-cb-750-hornet-2023-2024\/","title":{"rendered":"H.085.L2P \u2013  HONDA CB 750 HORNET 2023 > 2024"},"content":{"rendered":"<p>Concebidos para melhorar a <strong>est\u00e9tica, som e desempenho<\/strong> da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem <strong>distinguir<\/strong> pelo <strong>aspeto<\/strong> das suas motos.<\/p>\n<p>GP PRO, fabricado por <strong>soldagem TIG semi-manual<\/strong>, mostra um <strong>design compacto e essencial<\/strong> e um <strong>som agressivo<\/strong>. Inspirado no mundo da <strong>competi\u00e7\u00e3o<\/strong>, o tubo de escape est\u00e1 equipado com uma <strong>rede de prote\u00e7\u00e3o remov\u00edvel<\/strong> que esconde redutor de decib\u00e9is. Este silenciador ostenta a log\u00f3tipo caracter\u00edstico da Mivv criado por tecnologia laser.<\/p>\n<p>Possui um corpo central de <strong>carbono<\/strong> com <strong>acabamento brilhante<\/strong>. \u00c9 o <strong>produto ideal para aqueles que necessitam de um visual e tecnologia de ponta.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Concebidos para melhorar a est\u00e9tica, som e desempenho da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem distinguir pelo aspeto das suas motos. GP PRO, fabricado por soldagem TIG semi-manual, mostra um design compacto e essencial e um som agressivo. [&hellip;]<\/p>\n","protected":false},"featured_media":63702,"template":"","meta":{"_acf_changed":false},"product_brand":[24059,24052,23849],"product_cat":[705],"product_tag":[],"class_list":{"0":"post-100262","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2023-cb-750-hornet","7":"product_brand-cb-750-hornet","8":"product_brand-honda","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/100262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/63702"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=100262"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=100262"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=100262"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=100262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}