{"id":100297,"date":"2026-04-21T14:39:15","date_gmt":"2026-04-21T12:39:15","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/acc-070-0-honda-cb-750-hornet-2023-2024\/"},"modified":"2026-04-21T14:39:15","modified_gmt":"2026-04-21T12:39:15","slug":"acc-070-0-honda-cb-750-hornet-2023-2024","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/acc-070-0-honda-cb-750-hornet-2023-2024\/","title":{"rendered":"ACC.070.0 \u2013 HONDA CB 750 HORNET 2023> 2024"},"content":{"rendered":"<p>Esta prote\u00e7\u00e3o t\u00e9rmica em <strong>fibra de carbono<\/strong> foi projetada <strong>exclusivamente<\/strong> para o sistema de escape desta moto. Este produto <strong>opcional<\/strong>, de f\u00e1cil instala\u00e7\u00e3o, d\u00e1 uma apar\u00eancia <strong>mais desportiva<\/strong> a todo o sistema de escape e <strong>evita o contacto<\/strong> direto com as partes do sistema onde s\u00e3o atingidos <strong>picos de calor elevados<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta prote\u00e7\u00e3o t\u00e9rmica em fibra de carbono foi projetada exclusivamente para o sistema de escape desta moto. Este produto opcional, de f\u00e1cil instala\u00e7\u00e3o, d\u00e1 uma apar\u00eancia mais desportiva a todo o sistema de escape e evita o contacto direto com as partes do sistema onde s\u00e3o atingidos picos de calor elevados.<\/p>\n","protected":false},"featured_media":5782,"template":"","meta":{"_acf_changed":false},"product_brand":[24059,24052,23849],"product_cat":[21537],"product_tag":[],"class_list":{"0":"post-100297","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2023-cb-750-hornet","7":"product_brand-cb-750-hornet","8":"product_brand-honda","9":"product_cat-proteccao-termica","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/100297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/5782"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=100297"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=100297"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=100297"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=100297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}