{"id":101221,"date":"2026-04-21T14:47:16","date_gmt":"2026-04-21T12:47:16","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/z-004-sc4b-zontes-zt-125-gk-2021-2024\/"},"modified":"2026-04-21T14:47:16","modified_gmt":"2026-04-21T12:47:16","slug":"z-004-sc4b-zontes-zt-125-gk-2021-2024","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/z-004-sc4b-zontes-zt-125-gk-2021-2024\/","title":{"rendered":"Z.004.SC4B \u2013 ZONTES ZT 125 GK 2021 > 2024"},"content":{"rendered":"<p>Concebidos para melhorar a <strong>est\u00e9tica, som e desempenho<\/strong> da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem <strong>distinguir<\/strong> pelo <strong>aspeto<\/strong> das suas motos.<\/p>\n<p>A linha Mivv <strong>X-M1<\/strong>, o resultado da experi\u00eancia adquirida nos Campeonato Mundiais de <strong>MotoGP<\/strong> e <strong>Moto2<\/strong>, \u00e9 a s\u00edntese perfeita entre <strong>estilo de corrida<\/strong> e <strong>desempenho<\/strong>. Com um <strong>design<\/strong> semelhante aos escapes feitos para o Campeonato Mundial, o silenciador <strong>X-M1<\/strong> tem uma forma <strong>c\u00f3nica<\/strong> e dimens\u00f5es <strong>compactas<\/strong> e \u00e9 capaz de soltar o som <strong>cativante<\/strong> da MIVV.<\/p>\n<p>A vers\u00e3o <strong>Preta<\/strong> apresenta um corpo central em a\u00e7o inoxid\u00e1vel 304 preto com efeito <strong>&#8220;Black Moon&#8221;<\/strong>, acabamento obtido gra\u00e7as a um processo especial de pintura \u00e0 base de cer\u00e2mica.<\/p>\n<p><strong>X-M1 pure Italian style<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>N\u00c3O APROVADO<\/p>\n","protected":false},"featured_media":4620,"template":"","meta":{"_acf_changed":false},"product_brand":[28759,28805,28767],"product_cat":[19573],"product_tag":[],"class_list":{"0":"post-101221","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2021-zt-125-gk","7":"product_brand-zontes","8":"product_brand-zt-125-gk","9":"product_cat-planta-completa","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/101221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/4620"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=101221"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=101221"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=101221"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=101221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}