{"id":101606,"date":"2026-04-21T14:51:06","date_gmt":"2026-04-21T12:51:06","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/b-042-lr1tb-bmw-r-1300-gs-2024-2024\/"},"modified":"2026-04-21T14:51:06","modified_gmt":"2026-04-21T12:51:06","slug":"b-042-lr1tb-bmw-r-1300-gs-2024-2024","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/b-042-lr1tb-bmw-r-1300-gs-2024-2024\/","title":{"rendered":"B.042.LR1TB &#8211; BMW R 1300 GS 2024 > 2024"},"content":{"rendered":"<p>Concebidos para melhorar a <strong>est\u00e9tica, som e desempenho<\/strong> da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem <strong>distinguir<\/strong> pelo <strong>aspeto<\/strong> das suas motos.<\/p>\n<p>Os escapes da linha <strong>SR-1<\/strong> s\u00e3o dedicados principalmente \u00e0s superbikes e hypernaked. <strong>SR-1<\/strong> herda toda a experi\u00eancia adquirida nos v\u00e1rios campeonatos mundiais <strong>MotoGp &#8211; Moto2 &#8211; Moto3<\/strong>. Terminado com grande aten\u00e7\u00e3o pelos detalhes, garante uma melhoria na <strong>apar\u00eancia<\/strong> e <strong>desempenho<\/strong> da moto.<\/p>\n<p>Esta vers\u00e3o \u00e9 caracterizada por um <strong>corpo de tit\u00e2nio de forma hexagonal com um acabamento preto<\/strong> e pela presen\u00e7a de um <strong>copo de carbono<\/strong> com trama em T capaz de suportar tens\u00f5es de alta temperatura t\u00edpicas <strong>do mundo das corridas<\/strong>. Em compara\u00e7\u00e3o com o escape de s\u00e9rie o SR-1 em <strong>tit\u00e2nio<\/strong> garante uma <strong>redu\u00e7\u00e3o de peso<\/strong> consider\u00e1vel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Compat\u00edvel com sacos laterais originais<\/p>\n","protected":false},"featured_media":65461,"template":"","meta":{"_acf_changed":false},"product_brand":[22470,22106,22463],"product_cat":[705],"product_tag":[],"class_list":{"0":"post-101606","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2024-r-1300-gs","7":"product_brand-bmw","8":"product_brand-r-1300-gs","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/101606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/65461"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=101606"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=101606"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=101606"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=101606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}