{"id":101984,"date":"2026-04-21T14:54:27","date_gmt":"2026-04-21T12:54:27","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/ko-001-ldkx-kove-450-rally-2023-2024\/"},"modified":"2026-04-21T14:54:27","modified_gmt":"2026-04-21T12:54:27","slug":"ko-001-ldkx-kove-450-rally-2023-2024","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/ko-001-ldkx-kove-450-rally-2023-2024\/","title":{"rendered":"KO.001.LDKX &#8211; KOVE 450 RALLY 2023 > 2024"},"content":{"rendered":"<p>Concebidos para melhorar a <strong>est\u00e9tica, som e desempenho<\/strong> da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem <strong>distinguir<\/strong> pelo <strong>aspeto<\/strong> das suas motos.<\/p>\n<p>O projeto Dakar \u00e9 o resultado da experi\u00eancia da I&#038;D no \u00e2mbito das <strong>competi\u00e7\u00f5es de rali<\/strong>. <\/p>\n<p>O resultado obtido \u00e9 um <strong>escape essencial e robusto<\/strong> adequado para aqueles que preferem um off road mais <strong>exigente<\/strong>.<\/p>\n<p>O escape \u00e9  feito de a\u00e7o <strong>inoxid\u00e1vel 304 natural<\/strong> com a adi\u00e7\u00e3o de um acabamento especial <strong>&#8220;perlead&#8221;<\/strong> que o torna <strong>&#8220;altamente resistente.&#8221;<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Concebidos para melhorar a est\u00e9tica, som e desempenho da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem distinguir pelo aspeto das suas motos. O projeto Dakar \u00e9 o resultado da experi\u00eancia da I&#038;D no \u00e2mbito das competi\u00e7\u00f5es de rali. O [&hellip;]<\/p>\n","protected":false},"featured_media":62533,"template":"","meta":{"_acf_changed":false},"product_brand":[25760,25753,25746],"product_cat":[705],"product_tag":[],"class_list":{"0":"post-101984","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2023-450-rally","7":"product_brand-450-rally","8":"product_brand-kove","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/101984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/62533"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=101984"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=101984"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=101984"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=101984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}