{"id":102586,"date":"2026-04-21T15:00:00","date_gmt":"2026-04-21T13:00:00","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/acc-070-0-cf-moto-800-mt-2025-2026\/"},"modified":"2026-04-21T15:00:00","modified_gmt":"2026-04-21T13:00:00","slug":"acc-070-0-cf-moto-800-mt-2025-2026","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/acc-070-0-cf-moto-800-mt-2025-2026\/","title":{"rendered":"ACC.070.0 \u2013 CF MOTO 800 MT 2025 > 2026"},"content":{"rendered":"<p>Esta prote\u00e7\u00e3o t\u00e9rmica em <strong>fibra de carbono<\/strong> foi projetada <strong>exclusivamente<\/strong> para o sistema de escape desta moto. Este produto <strong>opcional<\/strong>, de f\u00e1cil instala\u00e7\u00e3o, d\u00e1 uma apar\u00eancia <strong>mais desportiva<\/strong> a todo o sistema de escape e <strong>evita o contacto<\/strong> direto com as partes do sistema onde s\u00e3o atingidos <strong>picos de calor elevados<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta prote\u00e7\u00e3o t\u00e9rmica em fibra de carbono foi projetada exclusivamente para o sistema de escape desta moto. Este produto opcional, de f\u00e1cil instala\u00e7\u00e3o, d\u00e1 uma apar\u00eancia mais desportiva a todo o sistema de escape e evita o contacto direto com as partes do sistema onde s\u00e3o atingidos picos de calor elevados.<\/p>\n","protected":false},"featured_media":4932,"template":"","meta":{"_acf_changed":false},"product_brand":[22750,22736,22568],"product_cat":[21537],"product_tag":[],"class_list":{"0":"post-102586","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2025-2026-10709","7":"product_brand-800-mt","8":"product_brand-cf-moto","9":"product_cat-proteccao-termica","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/102586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/4932"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=102586"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=102586"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=102586"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=102586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}