{"id":102691,"date":"2026-04-21T15:00:53","date_gmt":"2026-04-21T13:00:53","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/h-085-lxbp-honda-cb-750-hornet-2025-2026\/"},"modified":"2026-04-21T15:00:53","modified_gmt":"2026-04-21T13:00:53","slug":"h-085-lxbp-honda-cb-750-hornet-2025-2026","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/h-085-lxbp-honda-cb-750-hornet-2025-2026\/","title":{"rendered":"H.085.LXBP \u2013  HONDA CB 750 HORNET 2025 > 2026"},"content":{"rendered":"<p>Concebidos para melhorar a <strong>est\u00e9tica, som e desempenho<\/strong> da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem <strong>distinguir<\/strong> pelo <strong>aspeto<\/strong> das suas motos.<\/p>\n<p>GP PRO, fabricado por <strong>soldagem TIG semi-manual<\/strong>, mostra um <strong>design compacto e essencial<\/strong> e um <strong>som agressivo<\/strong>. Inspirado no mundo da <strong>competi\u00e7\u00e3o<\/strong>, o tubo de escape est\u00e1 equipado com uma <strong>rede de prote\u00e7\u00e3o remov\u00edvel<\/strong> que esconde redutor de decib\u00e9is. Este silenciador ostenta a log\u00f3tipo caracter\u00edstico da Mivv criado por tecnologia laser.<\/p>\n<p>Apresenta um corpo central em a\u00e7o inoxid\u00e1vel preto com efeito <strong>&#8220;Black Moon&#8221;<\/strong>, obtido gra\u00e7as a um processo especial de pintura \u00e0 base de cer\u00e2mica que confere ao produto um <strong>aspeto mais agressivo<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Concebidos para melhorar a est\u00e9tica, som e desempenho da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem distinguir pelo aspeto das suas motos. GP PRO, fabricado por soldagem TIG semi-manual, mostra um design compacto e essencial e um som agressivo. [&hellip;]<\/p>\n","protected":false},"featured_media":63719,"template":"","meta":{"_acf_changed":false},"product_brand":[24066,24052,23849],"product_cat":[705],"product_tag":[],"class_list":{"0":"post-102691","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2025-2026-10820","7":"product_brand-cb-750-hornet","8":"product_brand-honda","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/102691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/63719"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=102691"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=102691"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=102691"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=102691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}