{"id":102712,"date":"2026-04-21T15:01:04","date_gmt":"2026-04-21T13:01:04","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/h-080-ldrb-honda-forza-750-2025-2026\/"},"modified":"2026-04-21T15:01:04","modified_gmt":"2026-04-21T13:01:04","slug":"h-080-ldrb-honda-forza-750-2025-2026","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/h-080-ldrb-honda-forza-750-2025-2026\/","title":{"rendered":"H.080.LDRB \u2013 HONDA FORZA 750 2025 > 2026"},"content":{"rendered":"<p>Concebidos para melhorar a <strong>est\u00e9tica, som e desempenho<\/strong> da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem <strong>distinguir<\/strong> pelo <strong>aspeto<\/strong> das suas motos.<\/p>\n<p>O escape DELTA RACE apresenta uma <strong>forma exclusiva<\/strong> que, atrav\u00e9s de uma transforma\u00e7\u00e3o gradual, de c\u00f3nico torna-se em <strong>hexagonal<\/strong>. H\u00e1 muitos detalhes que o tornam \u00fanico, como a tampa de carbono sarja 3K; o suporte do per\u00edmetro com <strong>rebitagem dupla<\/strong>, a bucha de entrada especialmente maquinada para oferecer a m\u00e1xima precis\u00e3o no acoplamento. Este escape ostenta a log\u00f3tipo caracter\u00edstico da Mivv criado por tecnologia laser.<\/p>\n<p>Apresenta um corpo central em a\u00e7o inoxid\u00e1vel preto com efeito <strong>&#8220;Black Moon&#8221;<\/strong>, obtido gra\u00e7as a um processo especial de pintura \u00e0 base de cer\u00e2mica que confere ao produto um <strong>aspeto mais agressivo<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Concebidos para melhorar a est\u00e9tica, som e desempenho da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem distinguir pelo aspeto das suas motos. O escape DELTA RACE apresenta uma forma exclusiva que, atrav\u00e9s de uma transforma\u00e7\u00e3o gradual, de c\u00f3nico torna-se [&hellip;]<\/p>\n","protected":false},"featured_media":63736,"template":"","meta":{"_acf_changed":false},"product_brand":[24500,24486,23849],"product_cat":[705],"product_tag":[],"class_list":{"0":"post-102712","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2025-2026-10378","7":"product_brand-forza-750","8":"product_brand-honda","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/102712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/63736"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=102712"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=102712"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=102712"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=102712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}