{"id":102726,"date":"2026-04-21T15:01:34","date_gmt":"2026-04-21T13:01:34","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/h-068-l2p-honda-cb-1000-r-2025-2025\/"},"modified":"2026-04-21T15:01:34","modified_gmt":"2026-04-21T13:01:34","slug":"h-068-l2p-honda-cb-1000-r-2025-2025","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/h-068-l2p-honda-cb-1000-r-2025-2025\/","title":{"rendered":"H.068.L2P \u2013 HONDA CB 1000 R 2025 > 2025"},"content":{"rendered":"<p>Concebidos para melhorar a <strong>est\u00e9tica, som e desempenho<\/strong> da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem <strong>distinguir<\/strong> pelo <strong>aspeto<\/strong> das suas motos.<\/p>\n<p>GP PRO, fabricado por <strong>soldagem TIG semi-manual<\/strong>, mostra um <strong>design compacto e essencial<\/strong> e um <strong>som agressivo<\/strong>. Inspirado no mundo da <strong>competi\u00e7\u00e3o<\/strong>, o tubo de escape est\u00e1 equipado com uma <strong>rede de prote\u00e7\u00e3o remov\u00edvel<\/strong> que esconde redutor de decib\u00e9is. Este silenciador ostenta a log\u00f3tipo caracter\u00edstico da Mivv criado por tecnologia laser.<\/p>\n<p>Possui um corpo central de <strong>carbono<\/strong> com <strong>acabamento brilhante<\/strong>. \u00c9 o <strong>produto ideal para aqueles que necessitam de um visual e tecnologia de ponta.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Concebidos para melhorar a est\u00e9tica, som e desempenho da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem distinguir pelo aspeto das suas motos. GP PRO, fabricado por soldagem TIG semi-manual, mostra um design compacto e essencial e um som agressivo. [&hellip;]<\/p>\n","protected":false},"featured_media":63702,"template":"","meta":{"_acf_changed":false},"product_brand":[23884,23849],"product_cat":[705],"product_tag":[],"class_list":{"0":"post-102726","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-cb-1000-r","7":"product_brand-honda","8":"product_cat-slip-on","10":"first","11":"instock","12":"shipping-taxable","13":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/102726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/63702"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=102726"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=102726"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=102726"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=102726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}