{"id":102733,"date":"2026-04-21T15:01:37","date_gmt":"2026-04-21T13:01:37","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/h-068-lm3b-honda-cb-1000-r-2025-2025\/"},"modified":"2026-04-21T15:01:37","modified_gmt":"2026-04-21T13:01:37","slug":"h-068-lm3b-honda-cb-1000-r-2025-2025","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/h-068-lm3b-honda-cb-1000-r-2025-2025\/","title":{"rendered":"H.068.LM3B \u2013 HONDA CB 1000 R 2025 > 2025"},"content":{"rendered":"<p>Concebidos para melhorar a <strong>est\u00e9tica, som e desempenho<\/strong> da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem <strong>distinguir<\/strong> pelo <strong>aspeto<\/strong> das suas motos.<\/p>\n<p>A linha <strong>MK3<\/strong>, resultante da experi\u00eancia adquirida nos campeonatos mundiais de <strong>Moto3 e Moto2<\/strong>, \u00e9 a s\u00edntese perfeita entre <strong>desempenho e tecnologia<\/strong>. Com um <strong>design<\/strong> semelhante aos escapes feitos para <strong>compeonatos mundiais de Moto3<\/strong>, o MK3 \u00e9 um produto <strong>compacto<\/strong>, capaz de libertar o cativante <strong>som da mivv<\/strong>.<\/p>\n<p>A vers\u00e3o Preta apresenta um corpo central em a\u00e7o inoxid\u00e1vel 304 preto com um efeito <strong>&#8220;Black Moon&#8221;<\/strong>, um acabamento obtido gra\u00e7as a um processo especial de pintura \u00e0 base de cer\u00e2mica que, em combina\u00e7\u00e3o com a rede de prote\u00e7\u00e3o na tampa de sa\u00edda, confere ao produto um <strong>aspeto mais agressivo<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Concebidos para melhorar a est\u00e9tica, som e desempenho da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem distinguir pelo aspeto das suas motos. A linha MK3, resultante da experi\u00eancia adquirida nos campeonatos mundiais de Moto3 e Moto2, \u00e9 a s\u00edntese [&hellip;]<\/p>\n","protected":false},"featured_media":64218,"template":"","meta":{"_acf_changed":false},"product_brand":[23884,23849],"product_cat":[705],"product_tag":[],"class_list":{"0":"post-102733","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-cb-1000-r","7":"product_brand-honda","8":"product_cat-slip-on","10":"first","11":"instock","12":"shipping-taxable","13":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/102733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/64218"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=102733"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=102733"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=102733"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=102733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}