{"id":103636,"date":"2026-04-21T15:09:11","date_gmt":"2026-04-21T13:09:11","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/d-055-lc5b-ducati-hypermotard-698-mono-2024-2026\/"},"modified":"2026-04-21T15:09:11","modified_gmt":"2026-04-21T13:09:11","slug":"d-055-lc5b-ducati-hypermotard-698-mono-2024-2026","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/d-055-lc5b-ducati-hypermotard-698-mono-2024-2026\/","title":{"rendered":"D.055.LC5B &#8211; DUCATI HYPERMOTARD 698 MONO 2024 > 2026"},"content":{"rendered":"<p>Concebidos para melhorar a <strong>est\u00e9tica, som e desempenho<\/strong> da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem <strong>distinguir<\/strong> pelo <strong>aspeto<\/strong> das suas motos.<\/p>\n<p>A linha Mivv <strong>X-M5<\/strong> fruto da experi\u00eancia adquirida nos Campeonatos Mundiais de <strong>MotoGP, Moto2<\/strong> e <strong>Moto3<\/strong>, \u00e9 a s\u00edntese perfeita entre <strong>estilo de corrida<\/strong> e <strong>desempenho<\/strong>. Com um <strong>design<\/strong> inspirado nos escapes feitos para o Campeonato Mundial de motociclismo, o silenciador <strong>X-M5<\/strong> tem uma forma <strong>c\u00f3nica<\/strong> e dimens\u00f5es <strong>compactas<\/strong> capazes de libertar o cativante <strong>som<\/strong> MIVV.<\/p>\n<p>Est\u00e1 equipado com um suporte de <strong>carbono<\/strong> twill 3K e est\u00e1 equipado com uma <strong>grade de prote\u00e7\u00e3o remov\u00edvel<\/strong> que esconde o dB-killer.<\/p>\n<p>A vers\u00e3o <strong>Preta<\/strong> apresenta um corpo central em a\u00e7o inoxid\u00e1vel 304 preto com efeito <strong>&#8220;Black Moon&#8221;<\/strong>, acabamento obtido gra\u00e7as a um processo especial de pintura \u00e0 base de cer\u00e2mica.<\/p>\n<p><strong>X-M5 puro estilo italiano<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Concebidos para melhorar a est\u00e9tica, som e desempenho da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem distinguir pelo aspeto das suas motos. A linha Mivv X-M5 fruto da experi\u00eancia adquirida nos Campeonatos Mundiais de MotoGP, Moto2 e Moto3, \u00e9 [&hellip;]<\/p>\n","protected":false},"featured_media":64959,"template":"","meta":{"_acf_changed":false},"product_brand":[22911,22771,22904],"product_cat":[850],"product_tag":[],"class_list":{"0":"post-103636","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2024-2026-11504","7":"product_brand-ducati","8":"product_brand-hypermotard-698-mono","9":"product_cat-2-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/103636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/64959"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=103636"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=103636"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=103636"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=103636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}