{"id":103776,"date":"2026-04-21T15:10:51","date_gmt":"2026-04-21T13:10:51","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/b-044-lrx-bmw-f-800-gs-2025-2026\/"},"modified":"2026-04-21T15:10:51","modified_gmt":"2026-04-21T13:10:51","slug":"b-044-lrx-bmw-f-800-gs-2025-2026","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/b-044-lrx-bmw-f-800-gs-2025-2026\/","title":{"rendered":"B.044.LRX &#8211; BMW F 800 GS 2025 > 2026"},"content":{"rendered":"<p>Concebidos para melhorar a <strong>est\u00e9tica, som e desempenho<\/strong> da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem <strong>distinguir<\/strong> pelo <strong>aspeto<\/strong> das suas motos.<\/p>\n<p><strong>Design moderno<\/strong> e excelente desempenho s\u00e3o as principais caracter\u00edsticas do escape SPEED EDGE, que combina tamb\u00e9m um som <strong>distintamente desportivo<\/strong>.<\/p>\n<p>Com um corpo em <strong>a\u00e7o inoxid\u00e1vel escovado<\/strong> com tampa de <strong>carbono<\/strong> e cinta de fixa\u00e7\u00e3o, este escape tem uma forma <strong>hexagonal<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Concebidos para melhorar a est\u00e9tica, som e desempenho da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem distinguir pelo aspeto das suas motos. Design moderno e excelente desempenho s\u00e3o as principais caracter\u00edsticas do escape SPEED EDGE, que combina tamb\u00e9m um [&hellip;]<\/p>\n","protected":false},"featured_media":63230,"template":"","meta":{"_acf_changed":false},"product_brand":[22176,22106,22155],"product_cat":[705],"product_tag":[],"class_list":{"0":"post-103776","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2025-2026-347","7":"product_brand-bmw","8":"product_brand-f-800-gs","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/103776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/63230"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=103776"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=103776"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=103776"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=103776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}