{"id":103783,"date":"2026-04-21T15:10:54","date_gmt":"2026-04-21T13:10:54","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/cf-005-ldkb-cf-moto-450-mt-2025-2026\/"},"modified":"2026-04-21T15:10:54","modified_gmt":"2026-04-21T13:10:54","slug":"cf-005-ldkb-cf-moto-450-mt-2025-2026","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/cf-005-ldkb-cf-moto-450-mt-2025-2026\/","title":{"rendered":"CF.005.LDKB &#8211; CF MOTO 450 MT 2025> 2026"},"content":{"rendered":"<p>Concebidos para melhorar a <strong>est\u00e9tica, som e desempenho<\/strong> da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem <strong>distinguir<\/strong> pelo <strong>aspeto<\/strong> das suas motos.<\/p>\n<p>O projeto Dakar \u00e9 o resultado da experi\u00eancia da I&#038;D no \u00e2mbito das <strong>competi\u00e7\u00f5es de rali<\/strong>. <\/p>\n<p>O resultado obtido \u00e9 um <strong>escape essencial e robusto<\/strong> adequado para aqueles que preferem um off road mais <strong>exigente<\/strong>.<\/p>\n<p>A vers\u00e3o <strong>Preta<\/strong> apresenta um corpo central em a\u00e7o inoxid\u00e1vel 304 <strong>preto<\/strong> com efeito <strong>&#8220;Black Moon&#8221;<\/strong>, acabamento obtido gra\u00e7as a um processo especial de pintura \u00e0 base de <strong>cer\u00e2mica<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>N\u00e3o compat\u00edvel com o suporte da matr\u00edcula e pisca-pisca originais.<\/p>\n","protected":false},"featured_media":64431,"template":"","meta":{"_acf_changed":false},"product_brand":[22603,22589,22568],"product_cat":[705],"product_tag":[],"class_list":{"0":"post-103783","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2025-2026-11486","7":"product_brand-450-mt","8":"product_brand-cf-moto","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/103783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/64431"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=103783"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=103783"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=103783"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=103783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}