{"id":103986,"date":"2026-04-21T15:12:31","date_gmt":"2026-04-21T13:12:31","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/h-094-sm3b-honda-cb-650-r-2024-2026\/"},"modified":"2026-04-21T15:12:31","modified_gmt":"2026-04-21T13:12:31","slug":"h-094-sm3b-honda-cb-650-r-2024-2026","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/h-094-sm3b-honda-cb-650-r-2024-2026\/","title":{"rendered":"H.094.SM3B &#8211; HONDA CB 650 R 2024 > 2026"},"content":{"rendered":"<p>Concebidos para melhorar a <strong>est\u00e9tica, som e desempenho<\/strong> da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem <strong>distinguir<\/strong> pelo <strong>aspeto<\/strong> das suas motos.<\/p>\n<p>A linha <strong>MK3<\/strong>, resultante da experi\u00eancia adquirida nos campeonatos mundiais de <strong>Moto3 e Moto2<\/strong>, \u00e9 a s\u00edntese perfeita entre <strong>desempenho e tecnologia<\/strong>. Com um <strong>design<\/strong> semelhante aos escapes feitos para <strong>compeonatos mundiais de Moto3<\/strong>, o MK3 \u00e9 um produto <strong>compacto<\/strong>, capaz de libertar o cativante <strong>som da mivv<\/strong>.<\/p>\n<p>A vers\u00e3o Preta apresenta um corpo central em a\u00e7o inoxid\u00e1vel 304 preto com um efeito <strong>&#8220;Black Moon&#8221;<\/strong>, um acabamento obtido gra\u00e7as a um processo especial de pintura \u00e0 base de cer\u00e2mica que, em combina\u00e7\u00e3o com a rede de prote\u00e7\u00e3o na tampa de sa\u00edda, confere ao produto um <strong>aspeto mais agressivo<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PROTETOR DE CALOR DE CARBONO INCLU\u00cdDO. N\u00c3O APROVADO. A instala\u00e7\u00e3o deste sistema de escape sem a switch-off key pode fazer com que a luz de aviso do motor se acenda.<\/p>\n","protected":false},"featured_media":64218,"template":"","meta":{"_acf_changed":false},"product_brand":[24045,24031,23849],"product_cat":[19573],"product_tag":[],"class_list":{"0":"post-103986","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2024-2026-9188","7":"product_brand-cb-650-r","8":"product_brand-honda","9":"product_cat-planta-completa","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/103986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/64218"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=103986"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=103986"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=103986"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=103986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}