{"id":104973,"date":"2026-04-21T15:21:45","date_gmt":"2026-04-21T13:21:45","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/hd-005-lh1ba-harley-davidson-road-king-classic-special-2017-2023\/"},"modified":"2026-04-21T15:21:45","modified_gmt":"2026-04-21T13:21:45","slug":"hd-005-lh1ba-harley-davidson-road-king-classic-special-2017-2023","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/hd-005-lh1ba-harley-davidson-road-king-classic-special-2017-2023\/","title":{"rendered":"HD.005.LH1BA &#8211; HARLEY DAVIDSON ROAD KING \/ CLASSIC \/ SPECIAL 2017 > 2023"},"content":{"rendered":"<p>Concebidos para melhorar a <strong>est\u00e9tica, som e desempenho<\/strong> da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem <strong>distinguir<\/strong> pelo <strong>aspeto<\/strong> das suas motos.<\/p>\n<p>Os escapes da linha HR-1 t\u00eam uma forma redonda montados com rebites pretos com um\u00a0<strong>aspeto especial<\/strong>. O tubo de sa\u00edda \u00e9 feito de\u00a0<strong>alum\u00ednio envernizado preto<\/strong>\u00a0ou\u00a0<strong>carbono &#8220;twill 3K look&#8221;<\/strong><\/p>\n<p>Apresenta um corpo central em a\u00e7o inoxid\u00e1vel preto com efeito <strong>&#8220;Black Moon&#8221;<\/strong>, obtido gra\u00e7as a um processo especial de pintura \u00e0 base de cer\u00e2mica que confere ao produto um <strong>aspeto &#8220;classic style&#8221;<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Concebidos para melhorar a est\u00e9tica, som e desempenho da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem distinguir pelo aspeto das suas motos. Os escapes da linha HR-1 t\u00eam uma forma redonda montados com rebites pretos com um\u00a0aspeto especial. O [&hellip;]<\/p>\n","protected":false},"featured_media":11471,"template":"","meta":{"_acf_changed":false},"product_brand":[23758,23632,23751],"product_cat":[850],"product_tag":[],"class_list":{"0":"post-104973","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2017-road-king-classic-special","7":"product_brand-harley-davidson","8":"product_brand-road-king-classic-special","9":"product_cat-2-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/104973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/11471"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=104973"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=104973"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=104973"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=104973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}