{"id":89153,"date":"2026-04-21T13:16:58","date_gmt":"2026-04-21T11:16:58","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/c-gl-0009-b-gilera-nexus-500-2004-2020\/"},"modified":"2026-04-21T13:16:58","modified_gmt":"2026-04-21T11:16:58","slug":"c-gl-0009-b-gilera-nexus-500-2004-2020","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/c-gl-0009-b-gilera-nexus-500-2004-2020\/","title":{"rendered":"C.GL.0009.B &#8211; GILERA NEXUS 500 2004 > 2020"},"content":{"rendered":"<p>Os escapes Mivv para scooters t\u00eam como objetivo melhorar o <strong>som<\/strong> e o <strong>desempenho<\/strong>, bem como o <strong>aspeto<\/strong> das pr\u00f3prias scooters. Uma mistura perfeita para uma scooter completamente <strong>especial<\/strong>.<\/p>\n<p>URBAN \u00e9 uma gama alternativa no que diz respeito ao <strong>aspeto<\/strong> e \u00e0s caracter\u00edsticas t\u00e9cnicas. Totalmente fabricado em <strong>a\u00e7o inoxid\u00e1vel escovado<\/strong>, combina <strong>estilo e pre\u00e7o<\/strong> de forma inteligente.<\/p>\n<p> A gama Urban tamb\u00e9m est\u00e1 dispon\u00edvel na vers\u00e3o catalisada, em conformidade com as normas Europeias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os escapes Mivv para scooters t\u00eam como objetivo melhorar o som e o desempenho, bem como o aspeto das pr\u00f3prias scooters. Uma mistura perfeita para uma scooter completamente especial. URBAN \u00e9 uma gama alternativa no que diz respeito ao aspeto e \u00e0s caracter\u00edsticas t\u00e9cnicas. Totalmente fabricado em a\u00e7o inoxid\u00e1vel escovado, combina estilo e pre\u00e7o de [&hellip;]<\/p>\n","protected":false},"featured_media":62549,"template":"","meta":{"_acf_changed":false},"product_brand":[23590,23534,23583],"product_cat":[705],"product_tag":[],"class_list":{"0":"post-89153","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2004-2012-nexus-500","7":"product_brand-gilera","8":"product_brand-nexus-500","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/89153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/62549"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=89153"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=89153"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=89153"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=89153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}