{"id":89510,"date":"2026-04-21T13:19:21","date_gmt":"2026-04-21T11:19:21","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/b-005-l7-bmw-r-1200-r-2008-2010\/"},"modified":"2026-04-21T13:19:21","modified_gmt":"2026-04-21T11:19:21","slug":"b-005-l7-bmw-r-1200-r-2008-2010","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/b-005-l7-bmw-r-1200-r-2008-2010\/","title":{"rendered":"B.005.L7 &#8211; BMW R 1200 R 2008 > 2010"},"content":{"rendered":"<p>Concebidos para melhorar a <strong>est\u00e9tica, som e desempenho<\/strong> da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem <strong>distinguir<\/strong> pelo <strong>aspeto<\/strong> das suas motos.<\/p>\n<p>A gama SUONO \u00e9 a <strong>combina\u00e7\u00e3o perfeita<\/strong> de <strong>apar\u00eancia, inova\u00e7\u00e3o e tecnologia<\/strong> aplicada. Para o seu design, escolhemos os <strong>melhores materiais<\/strong> para garantir a <strong>m\u00e1xima leveza<\/strong> ao produto.<\/p>\n<p>Totalmente fabricado em a\u00e7o inoxid\u00e1vel escovado resistente a altas temperaturas, este silenciador \u00e9 ideal para os entusiastas de motos com uma aten\u00e7\u00e3o especial ao <strong>design.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Concebidos para melhorar a est\u00e9tica, som e desempenho da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem distinguir pelo aspeto das suas motos. A gama SUONO \u00e9 a combina\u00e7\u00e3o perfeita de apar\u00eancia, inova\u00e7\u00e3o e tecnologia aplicada. Para o seu design, [&hellip;]<\/p>\n","protected":false},"featured_media":62590,"template":"","meta":{"_acf_changed":false},"product_brand":[22421,22106,22414],"product_cat":[705],"product_tag":[],"class_list":{"0":"post-89510","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2008-2010-r-1200-r","7":"product_brand-bmw","8":"product_brand-r-1200-r","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/89510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/62590"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=89510"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=89510"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=89510"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=89510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}