{"id":89552,"date":"2026-04-21T13:19:35","date_gmt":"2026-04-21T11:19:35","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/d-018-l2s-ducati-monster-800-2003-2020\/"},"modified":"2026-04-21T13:19:35","modified_gmt":"2026-04-21T11:19:35","slug":"d-018-l2s-ducati-monster-800-2003-2020","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/d-018-l2s-ducati-monster-800-2003-2020\/","title":{"rendered":"D.018.L2S \u2013 DUCATI MONSTER 800 2003 > 2020"},"content":{"rendered":"<p>Concebidos para melhorar a <strong>est\u00e9tica, som e desempenho<\/strong> da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem <strong>distinguir<\/strong> pelo <strong>aspeto<\/strong> das suas motos.<\/p>\n<p>Fabricado implementando as solu\u00e7\u00f5es t\u00e9cnicas dos modelos da <strong>competi\u00e7\u00e3o<\/strong>, o escape GP \u00e9 um silenciador redondo curto com sa\u00edda ampliada.<\/p>\n<p>O corpo central \u00e9 feito de <strong>carbono<\/strong>, um material que confere leveza e um car\u00e1ter <strong>desportivo<\/strong> ao silenciador.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Concebidos para melhorar a est\u00e9tica, som e desempenho da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem distinguir pelo aspeto das suas motos. Fabricado implementando as solu\u00e7\u00f5es t\u00e9cnicas dos modelos da competi\u00e7\u00e3o, o escape GP \u00e9 um silenciador redondo curto [&hellip;]<\/p>\n","protected":false},"featured_media":62619,"template":"","meta":{"_acf_changed":false},"product_brand":[23149,22771,23142],"product_cat":[850],"product_tag":[],"class_list":{"0":"post-89552","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2003-2005-monster-800","7":"product_brand-ducati","8":"product_brand-monster-800","9":"product_cat-2-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/89552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/62619"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=89552"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=89552"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=89552"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=89552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}