{"id":89601,"date":"2026-04-21T13:19:51","date_gmt":"2026-04-21T11:19:51","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/d-019-lx1-ducati-monster-695-2006-2020\/"},"modified":"2026-04-21T13:19:51","modified_gmt":"2026-04-21T11:19:51","slug":"d-019-lx1-ducati-monster-695-2006-2020","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/d-019-lx1-ducati-monster-695-2006-2020\/","title":{"rendered":"D.019.LX1 &#8211; DUCATI MONSTER 695 2006 > 2020"},"content":{"rendered":"<p>Concebidos para melhorar a <strong>est\u00e9tica, som e desempenho<\/strong> da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem <strong>distinguir<\/strong> pelo <strong>aspeto<\/strong> das suas motos.<\/p>\n<p>O escape OVAL \u00e9 perfeitamente adequado para todos os tipos de motos. Com a m\u00e1xima aten\u00e7\u00e3o aos detalhes, esta gama \u00e9 o melhor compromisso entre o <strong>visual<\/strong> e o <strong>desempenho<\/strong>. <\/p>\n<p>O a\u00e7o inoxid\u00e1vel <strong>escovado<\/strong> do corpo central enfatiza o <strong>acabamento natural<\/strong> deste material.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Concebidos para melhorar a est\u00e9tica, som e desempenho da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem distinguir pelo aspeto das suas motos. O escape OVAL \u00e9 perfeitamente adequado para todos os tipos de motos. Com a m\u00e1xima aten\u00e7\u00e3o aos [&hellip;]<\/p>\n","protected":false},"featured_media":62581,"template":"","meta":{"_acf_changed":false},"product_brand":[23079,22771,23072],"product_cat":[850],"product_tag":[],"class_list":{"0":"post-89601","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2006-2008-monster-695","7":"product_brand-ducati","8":"product_brand-monster-695","9":"product_cat-2-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/89601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/62581"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=89601"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=89601"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=89601"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=89601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}