{"id":89720,"date":"2026-04-21T13:20:36","date_gmt":"2026-04-21T11:20:36","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/d-011-lxb-ducati-monster-s2r-800-2005-2020\/"},"modified":"2026-04-21T13:20:36","modified_gmt":"2026-04-21T11:20:36","slug":"d-011-lxb-ducati-monster-s2r-800-2005-2020","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/d-011-lxb-ducati-monster-s2r-800-2005-2020\/","title":{"rendered":"D.011.LXB \u2013 DUCATI MONSTER S2R 800 2005 > 2020"},"content":{"rendered":"<p>Concebidos para melhorar a <strong>est\u00e9tica, som e desempenho<\/strong> da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem <strong>distinguir<\/strong> pelo <strong>aspeto<\/strong> das suas motos.<\/p>\n<p>Fabricado implementando as solu\u00e7\u00f5es t\u00e9cnicas dos modelos da <strong>competi\u00e7\u00e3o<\/strong>, o escape GP \u00e9 um silenciador redondo curto com sa\u00edda ampliada.<\/p>\n<p>Este escape apresenta um corpo central em a\u00e7o inoxid\u00e1vel preto com efeito <strong>&#8220;Black Moon&#8221;<\/strong> escovado, obtido com um processo de colora\u00e7\u00e3o especial que proporciona um aspeto mais <strong>agressivo<\/strong> ao silenciador.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Concebidos para melhorar a est\u00e9tica, som e desempenho da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem distinguir pelo aspeto das suas motos. Fabricado implementando as solu\u00e7\u00f5es t\u00e9cnicas dos modelos da competi\u00e7\u00e3o, o escape GP \u00e9 um silenciador redondo curto [&hellip;]<\/p>\n","protected":false},"featured_media":62610,"template":"","meta":{"_acf_changed":false},"product_brand":[23226,22771,23219],"product_cat":[850],"product_tag":[],"class_list":{"0":"post-89720","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2005-2007-monster-s2r-800","7":"product_brand-ducati","8":"product_brand-monster-s2r-800","9":"product_cat-2-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/89720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/62610"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=89720"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=89720"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=89720"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=89720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}