{"id":89825,"date":"2026-04-21T13:21:35","date_gmt":"2026-04-21T11:21:35","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/g-002-lxb-gilera-runner-200-2003-2004\/"},"modified":"2026-04-21T13:21:35","modified_gmt":"2026-04-21T11:21:35","slug":"g-002-lxb-gilera-runner-200-2003-2004","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/g-002-lxb-gilera-runner-200-2003-2004\/","title":{"rendered":"G.002.LXB &#8211; GILERA RUNNER 200 2003 > 2004"},"content":{"rendered":"<p>Os escapes Mivv para scooters t\u00eam como objetivo melhorar o <strong>som<\/strong> e o <strong>desempenho<\/strong>, bem como o <strong>aspeto<\/strong> das pr\u00f3prias scooters. Uma mistura perfeita para uma scooter completamente <strong>especial<\/strong>.<\/p>\n<p>Fabricado implementando as solu\u00e7\u00f5es t\u00e9cnicas dos modelos da <strong>competi\u00e7\u00e3o<\/strong>, o escape GP \u00e9 um silenciador redondo curto com sa\u00edda ampliada.<\/p>\n<p>Este escape apresenta um corpo central em a\u00e7o inoxid\u00e1vel preto com efeito <strong>&#8220;Black Moon&#8221;<\/strong> escovado, obtido com um processo de colora\u00e7\u00e3o especial que proporciona um aspeto mais <strong>agressivo<\/strong> ao silenciador.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os escapes Mivv para scooters t\u00eam como objetivo melhorar o som e o desempenho, bem como o aspeto das pr\u00f3prias scooters. Uma mistura perfeita para uma scooter completamente especial. Fabricado implementando as solu\u00e7\u00f5es t\u00e9cnicas dos modelos da competi\u00e7\u00e3o, o escape GP \u00e9 um silenciador redondo curto com sa\u00edda ampliada. Este escape apresenta um corpo central [&hellip;]<\/p>\n","protected":false},"featured_media":62610,"template":"","meta":{"_acf_changed":false},"product_brand":[23618,23534,23611],"product_cat":[705],"product_tag":[],"class_list":{"0":"post-89825","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2003-2004-runner-200","7":"product_brand-gilera","8":"product_brand-runner-200","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/89825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/62610"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=89825"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=89825"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=89825"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=89825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}