{"id":90147,"date":"2026-04-21T13:23:27","date_gmt":"2026-04-21T11:23:27","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/h-018-lc3-honda-hornet-600-2001-2002\/"},"modified":"2026-04-21T13:23:27","modified_gmt":"2026-04-21T11:23:27","slug":"h-018-lc3-honda-hornet-600-2001-2002","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/h-018-lc3-honda-hornet-600-2001-2002\/","title":{"rendered":"H.018.LC3 &#8211; Honda HORNET 600 2001 > 2002"},"content":{"rendered":"<p>Concebidos para melhorar a <strong>est\u00e9tica, som e desempenho<\/strong> da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem <strong>distinguir<\/strong> pelo <strong>aspeto<\/strong> das suas motos.<\/p>\n<p>O escape X-CONE destina-se principalmente a motos naked ou retro. Com uma forma <strong>c\u00f3nica<\/strong>, o seu aspeto foi cuidadosamente desenhado em cada detalhe.<\/p>\n<p>Feito de <strong>a\u00e7o inoxid\u00e1vel<\/strong> com acabamento <strong>escovado<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Concebidos para melhorar a est\u00e9tica, som e desempenho da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem distinguir pelo aspeto das suas motos. O escape X-CONE destina-se principalmente a motos naked ou retro. Com uma forma c\u00f3nica, o seu aspeto [&hellip;]<\/p>\n","protected":false},"featured_media":62816,"template":"","meta":{"_acf_changed":false},"product_brand":[24521,23849,24507],"product_cat":[705],"product_tag":[],"class_list":{"0":"post-90147","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2001-2002-hornet-600","7":"product_brand-honda","8":"product_brand-hornet-600","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/90147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/62816"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=90147"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=90147"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=90147"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=90147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}