{"id":90189,"date":"2026-04-21T13:23:41","date_gmt":"2026-04-21T11:23:41","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/h-034-lxb-honda-fmx-650-2005-2020\/"},"modified":"2026-04-21T13:23:41","modified_gmt":"2026-04-21T11:23:41","slug":"h-034-lxb-honda-fmx-650-2005-2020","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/h-034-lxb-honda-fmx-650-2005-2020\/","title":{"rendered":"H.034.LXB \u2013 Honda FMX 650 2005 > 2020"},"content":{"rendered":"<p>Concebidos para melhorar a <strong>est\u00e9tica, som e desempenho<\/strong> da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem <strong>distinguir<\/strong> pelo <strong>aspeto<\/strong> das suas motos.<\/p>\n<p>Fabricado implementando as solu\u00e7\u00f5es t\u00e9cnicas dos modelos da <strong>competi\u00e7\u00e3o<\/strong>, o escape GP \u00e9 um silenciador redondo curto com sa\u00edda ampliada.<\/p>\n<p>Este escape apresenta um corpo central em a\u00e7o inoxid\u00e1vel preto com efeito <strong>&#8220;Black Moon&#8221;<\/strong> escovado, obtido com um processo de colora\u00e7\u00e3o especial que proporciona um aspeto mais <strong>agressivo<\/strong> ao silenciador.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Concebidos para melhorar a est\u00e9tica, som e desempenho da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem distinguir pelo aspeto das suas motos. Fabricado implementando as solu\u00e7\u00f5es t\u00e9cnicas dos modelos da competi\u00e7\u00e3o, o escape GP \u00e9 um silenciador redondo curto [&hellip;]<\/p>\n","protected":false},"featured_media":62610,"template":"","meta":{"_acf_changed":false},"product_brand":[24451,24444,23849],"product_cat":[850],"product_tag":[],"class_list":{"0":"post-90189","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2005-2006-fmx-650","7":"product_brand-fmx-650","8":"product_brand-honda","9":"product_cat-2-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/90189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/62610"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=90189"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=90189"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=90189"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=90189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}