{"id":90231,"date":"2026-04-21T13:24:13","date_gmt":"2026-04-21T11:24:13","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/h-046-l9-honda-nc-700-s-x-2012-2020\/"},"modified":"2026-04-21T13:24:13","modified_gmt":"2026-04-21T11:24:13","slug":"h-046-l9-honda-nc-700-s-x-2012-2020","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/h-046-l9-honda-nc-700-s-x-2012-2020\/","title":{"rendered":"H.046.L9 &#8211; Honda NC 700 S \/ X 2012 > 2020"},"content":{"rendered":"<p>Concebidos para melhorar a <strong>est\u00e9tica, som e desempenho<\/strong> da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem <strong>distinguir<\/strong> pelo <strong>aspeto<\/strong> das suas motos.<\/p>\n<p>A gama SUONO \u00e9 a <strong>combina\u00e7\u00e3o perfeita<\/strong> de <strong>apar\u00eancia, inova\u00e7\u00e3o e tecnologia<\/strong> aplicada. Para o seu design, escolhemos os <strong>melhores materiais<\/strong> para garantir a <strong>m\u00e1xima leveza<\/strong> ao produto.<\/p>\n<p>Este escape apresenta um corpo central em a\u00e7o inoxid\u00e1vel preto com efeito <strong>&#8220;Black Moon&#8221;<\/strong> escovado, obtido com um processo de colora\u00e7\u00e3o especial que proporciona um aspeto mais <strong>agressivo<\/strong> ao silenciador.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Concebidos para melhorar a est\u00e9tica, som e desempenho da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem distinguir pelo aspeto das suas motos. A gama SUONO \u00e9 a combina\u00e7\u00e3o perfeita de apar\u00eancia, inova\u00e7\u00e3o e tecnologia aplicada. Para o seu design, [&hellip;]<\/p>\n","protected":false},"featured_media":62600,"template":"","meta":{"_acf_changed":false},"product_brand":[24612,23849,24605],"product_cat":[705],"product_tag":[],"class_list":{"0":"post-90231","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2012-2014-nc-700-s-x","7":"product_brand-honda","8":"product_brand-nc-700-s-x","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/90231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/62600"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=90231"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=90231"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=90231"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=90231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}