{"id":90322,"date":"2026-04-21T13:24:44","date_gmt":"2026-04-21T11:24:44","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/uh-032-lec-honda-cbr-1000-rr-2006-2007\/"},"modified":"2026-04-21T13:24:44","modified_gmt":"2026-04-21T11:24:44","slug":"uh-032-lec-honda-cbr-1000-rr-2006-2007","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/uh-032-lec-honda-cbr-1000-rr-2006-2007\/","title":{"rendered":"UH.032.LEC &#8211; Honda CBR 1000 RR 2006 > 2007"},"content":{"rendered":"<p>Concebidos para melhorar a <strong>est\u00e9tica, som e desempenho<\/strong> da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem <strong>distinguir<\/strong> pelo <strong>aspeto<\/strong> das suas motos.<\/p>\n<p>O escape OVAL \u00e9 perfeitamente adequado para todos os tipos de motos. Com a m\u00e1xima aten\u00e7\u00e3o aos detalhes, esta gama \u00e9 o melhor compromisso entre o <strong>visual<\/strong> e o <strong>desempenho<\/strong>. <\/p>\n<p>Com um corpo e tampa de <strong>carbono<\/strong> de alta resist\u00eancia t\u00e9rmica, o escape tem fendas abertas na tampa, um detalhe que proporciona um aspeto mais <strong>desportivo<\/strong> ao silenciador.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Concebidos para melhorar a est\u00e9tica, som e desempenho da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem distinguir pelo aspeto das suas motos. O escape OVAL \u00e9 perfeitamente adequado para todos os tipos de motos. Com a m\u00e1xima aten\u00e7\u00e3o aos [&hellip;]<\/p>\n","protected":false},"featured_media":24956,"template":"","meta":{"_acf_changed":false},"product_brand":[24101,24087,23849],"product_cat":[705],"product_tag":[],"class_list":{"0":"post-90322","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2006-2007-cbr-1000-rr","7":"product_brand-cbr-1000-rr","8":"product_brand-honda","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/90322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/24956"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=90322"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=90322"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=90322"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=90322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}