{"id":95950,"date":"2026-04-21T14:03:15","date_gmt":"2026-04-21T12:03:15","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/d-041-sm3c-ducati-monster-821-2018-2020\/"},"modified":"2026-04-21T14:03:15","modified_gmt":"2026-04-21T12:03:15","slug":"d-041-sm3c-ducati-monster-821-2018-2020","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/d-041-sm3c-ducati-monster-821-2018-2020\/","title":{"rendered":"D.041.SM3C \u2013 DUCATI MONSTER 821 2018 > 2020"},"content":{"rendered":"<p>Concebidos para melhorar a <strong>est\u00e9tica, som e desempenho<\/strong> da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem <strong>distinguir<\/strong> pelo <strong>aspeto<\/strong> das suas motos.<\/p>\n<p>A linha <strong>MK3<\/strong>, resultante da experi\u00eancia adquirida nos campeonatos mundiais de <strong>Moto3 e Moto2<\/strong>, \u00e9 a s\u00edntese perfeita entre <strong>desempenho e tecnologia<\/strong>. Com um <strong>design<\/strong> semelhante aos escapes feitos para <strong>compeonatos mundiais de Moto3<\/strong>, o MK3 \u00e9 um produto <strong>compacto<\/strong>, capaz de libertar o cativante <strong>som da mivv<\/strong>.<\/p>\n<p>A vers\u00e3o de Carbono apresenta um corpo central em <strong>carbono brilhante<\/strong> que, em combina\u00e7\u00e3o com a rede de prote\u00e7\u00e3o na tampa de sa\u00edda, confere ao produto um <strong>aspeto<\/strong> particularmente <strong>de alta tecnologia.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Concebidos para melhorar a est\u00e9tica, som e desempenho da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem distinguir pelo aspeto das suas motos. A linha MK3, resultante da experi\u00eancia adquirida nos campeonatos mundiais de Moto3 e Moto2, \u00e9 a s\u00edntese [&hellip;]<\/p>\n","protected":false},"featured_media":64181,"template":"","meta":{"_acf_changed":false},"product_brand":[23170,22771,23156],"product_cat":[705],"product_tag":[],"class_list":{"0":"post-95950","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2018-monster-821","7":"product_brand-ducati","8":"product_brand-monster-821","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/95950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/64181"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=95950"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=95950"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=95950"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=95950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}