{"id":96650,"date":"2026-04-21T14:08:34","date_gmt":"2026-04-21T12:08:34","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/e-005-c1-benelli-502c-2019-2024\/"},"modified":"2026-04-21T14:08:34","modified_gmt":"2026-04-21T12:08:34","slug":"e-005-c1-benelli-502c-2019-2024","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/e-005-c1-benelli-502c-2019-2024\/","title":{"rendered":"E.005.C1- BENELLI 502C 2019 > 2024"},"content":{"rendered":"<p>Os tubos Dekat de a\u00e7o inoxid\u00e1vel opcionais oferecem uma melhoria de <strong>desempenho<\/strong>, particularmente quando utilizados em conjunto com o silenciador mont\u00e1vel da Mivv. Este produto <strong>melhora<\/strong> a sua moto com <strong>um melhor aspeto<\/strong> e um <strong>som \u00fanico<\/strong>. Este produto <strong>n\u00e3o est\u00e1 aprovado<\/strong> de acordo com os regulamentos atuais para utiliza\u00e7\u00e3o de motos na estrada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os tubos Dekat de a\u00e7o inoxid\u00e1vel opcionais oferecem uma melhoria de desempenho, particularmente quando utilizados em conjunto com o silenciador mont\u00e1vel da Mivv. Este produto melhora a sua moto com um melhor aspeto e um som \u00fanico. Este produto n\u00e3o est\u00e1 aprovado de acordo com os regulamentos atuais para utiliza\u00e7\u00e3o de motos na estrada.<\/p>\n","protected":false},"featured_media":7125,"template":"","meta":{"_acf_changed":false},"product_brand":[21931,21924,21918],"product_cat":[21526],"product_tag":[],"class_list":{"0":"post-96650","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2019-502-c","7":"product_brand-502-c","8":"product_brand-benelli","9":"product_cat-tubo-de-remocao-de-cat","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/96650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/7125"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=96650"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=96650"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=96650"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=96650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}