{"id":96972,"date":"2026-04-21T14:11:21","date_gmt":"2026-04-21T12:11:21","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/a-012-lrb-aprilia-tuono-v4-1100-2018-2020\/"},"modified":"2026-04-21T14:11:21","modified_gmt":"2026-04-21T12:11:21","slug":"a-012-lrb-aprilia-tuono-v4-1100-2018-2020","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/a-012-lrb-aprilia-tuono-v4-1100-2018-2020\/","title":{"rendered":"A.012.LRB \u2013 APRILIA TUONO V4 1100 2018 > 2020"},"content":{"rendered":"<p>Concebidos para melhorar a <strong>est\u00e9tica, som e desempenho<\/strong> da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem <strong>distinguir<\/strong> pelo <strong>aspeto<\/strong> das suas motos.<\/p>\n<p><strong>Design moderno<\/strong> e excelente desempenho s\u00e3o as principais caracter\u00edsticas do escape SPEED EDGE, que combina tamb\u00e9m um som <strong>distintamente desportivo<\/strong>.<\/p>\n<p>Este escape possui uma tampa de <strong>carbono<\/strong> e uma cinta de fixa\u00e7\u00e3o e um corpo central de a\u00e7o inoxid\u00e1vel <strong>preto<\/strong> com um efeito \u201c<strong>Black Moon<\/strong>&#8221; escovado que proporciona um aspeto mais agressivo ao silenciador. Este produto tem uma forma <strong>hexagonal<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>APROVADO SOMENTE COM CATALISADOR ACC.045.A1 INSTALADO. A instala\u00e7\u00e3o deste escapamento requer o remapeamento da unidade de controle. Para obter mais informa\u00e7\u00f5es, leia as informa\u00e7\u00f5es t\u00e9cnicas na se\u00e7\u00e3o de documenta\u00e7\u00e3o.<\/p>\n","protected":false},"featured_media":62659,"template":"","meta":{"_acf_changed":false},"product_brand":[21889,21567,21882],"product_cat":[705],"product_tag":[],"class_list":{"0":"post-96972","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2018-tuono-v4-1100","7":"product_brand-aprilia","8":"product_brand-tuono-v4-1100","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/96972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/62659"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=96972"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=96972"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=96972"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=96972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}