{"id":97154,"date":"2026-04-21T14:12:42","date_gmt":"2026-04-21T12:12:42","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/mv-ho-0001-lv-honda-sh-300-2015-2020\/"},"modified":"2026-04-21T14:12:42","modified_gmt":"2026-04-21T12:12:42","slug":"mv-ho-0001-lv-honda-sh-300-2015-2020","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/mv-ho-0001-lv-honda-sh-300-2015-2020\/","title":{"rendered":"MV.HO.0001.LV \u2013 HONDA SH 300 2015 > 2020"},"content":{"rendered":"<p>Os escapes Mivv para scooters t\u00eam como objetivo melhorar o <strong>som<\/strong> e o <strong>desempenho<\/strong>, bem como o <strong>aspeto<\/strong> das pr\u00f3prias scooters. Uma mistura perfeita para uma scooter completamente <strong>especial<\/strong>.<\/p>\n<p>O escape\u00a0<strong>Mivv Mover<\/strong>\u00a0\u00e9 <strong>f\u00e1cil<\/strong> de instalar e capaz de garantir mais <strong>pot\u00eancia<\/strong>, mais bin\u00e1rio e menos <strong>peso<\/strong>. Em forma oval e com a tampa da extremidade feita de material Hpp, o Mivv Mover d\u00e1 \u00e0 sua scooter um\u00a0<strong>aspeto est\u00e9tico inimit\u00e1vel<\/strong>\u00a0e o\u00a0<strong>som inconfund\u00edvel da Mivv<\/strong>.\u00a0<\/p>\n<p>\u00c9 proposto em a\u00e7o inoxid\u00e1vel com um acabamento <strong>preto<\/strong>obtido gra\u00e7as a uma tinta cer\u00e2mica especial que d\u00e1 ao escape um efeito de\u00a0<strong>&#8220;black moon&#8221;<\/strong>.<\/p>\n<p>\u00a0O Mivv Mover est\u00e1 equipado com um catalisador que o torna aprovado de acordo com as normas CE\/ECE.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os escapes Mivv para scooters t\u00eam como objetivo melhorar o som e o desempenho, bem como o aspeto das pr\u00f3prias scooters. Uma mistura perfeita para uma scooter completamente especial. O escape\u00a0Mivv Mover\u00a0\u00e9 f\u00e1cil de instalar e capaz de garantir mais pot\u00eancia, mais bin\u00e1rio e menos peso. Em forma oval e com a tampa da extremidade [&hellip;]<\/p>\n","protected":false},"featured_media":64593,"template":"","meta":{"_acf_changed":false},"product_brand":[24787,23849,24766],"product_cat":[705],"product_tag":[],"class_list":{"0":"post-97154","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2015-2020-honda-sh-300","7":"product_brand-honda","8":"product_brand-sh-300","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/97154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/64593"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=97154"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=97154"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=97154"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=97154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}