{"id":97518,"date":"2026-04-21T14:16:02","date_gmt":"2026-04-21T12:16:02","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/b-038-ldrx-bmw-f-900-r-2020-2024\/"},"modified":"2026-04-21T14:16:02","modified_gmt":"2026-04-21T12:16:02","slug":"b-038-ldrx-bmw-f-900-r-2020-2024","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/b-038-ldrx-bmw-f-900-r-2020-2024\/","title":{"rendered":"B.038.LDRX \u2013 BMW F 900 R 2020 > 2024"},"content":{"rendered":"<p>Concebidos para melhorar a <strong>est\u00e9tica, som e desempenho<\/strong> da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem <strong>distinguir<\/strong> pelo <strong>aspeto<\/strong> das suas motos.<\/p>\n<p>O escape DELTA RACE apresenta uma <strong>forma exclusiva<\/strong> que, atrav\u00e9s de uma transforma\u00e7\u00e3o gradual, de c\u00f3nico torna-se em <strong>hexagonal<\/strong>. H\u00e1 muitos detalhes que o tornam \u00fanico, como a tampa de carbono sarja 3K; o suporte do per\u00edmetro com <strong>rebitagem dupla<\/strong>, a bucha de entrada especialmente maquinada para oferecer a m\u00e1xima precis\u00e3o no acoplamento. Este escape ostenta a log\u00f3tipo caracter\u00edstico da Mivv criado por tecnologia laser.<\/p>\n<p>Apresenta um corpo em a\u00e7o inoxid\u00e1vel escovado com efeito de <strong>&#8220;p\u00e9rola&#8221;<\/strong>, obtido com um processo de acabamento especial que confere ao produto um <strong>aspeto inimit\u00e1vel<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>HOMOLOGADO EURO 5. Compat\u00edvel apenas com os alforjes originais<\/p>\n","protected":false},"featured_media":7797,"template":"","meta":{"_acf_changed":false},"product_brand":[22246,22106,22239],"product_cat":[705],"product_tag":[],"class_list":{"0":"post-97518","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2020-f-900-r","7":"product_brand-bmw","8":"product_brand-f-900-r","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/97518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/7797"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=97518"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=97518"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=97518"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=97518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}