{"id":97728,"date":"2026-04-21T14:17:52","date_gmt":"2026-04-21T12:17:52","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/b-038-lc4t-bmw-f-900-r-2020-2024\/"},"modified":"2026-04-21T14:17:52","modified_gmt":"2026-04-21T12:17:52","slug":"b-038-lc4t-bmw-f-900-r-2020-2024","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/b-038-lc4t-bmw-f-900-r-2020-2024\/","title":{"rendered":"B.038.LC4T \u2013 BMW F 900 R 2020 > 2024"},"content":{"rendered":"<p>Concebidos para melhorar a <strong>est\u00e9tica, som e desempenho<\/strong> da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem <strong>distinguir<\/strong> pelo <strong>aspeto<\/strong> das suas motos.<\/p>\n<p>A linha Mivv <strong>X-M1<\/strong>, o resultado da experi\u00eancia adquirida nos Campeonato Mundiais de <strong>MotoGP<\/strong> e <strong>Moto2<\/strong>, \u00e9 a s\u00edntese perfeita entre <strong>estilo de corrida<\/strong> e <strong>desempenho<\/strong>. Com um <strong>design<\/strong> semelhante aos escapes feitos para o Campeonato Mundial, o silenciador <strong>X-M1<\/strong> tem uma forma <strong>c\u00f3nica<\/strong> e dimens\u00f5es <strong>compactas<\/strong> e \u00e9 capaz de soltar o som <strong>cativante<\/strong> da MIVV.<\/p>\n<p>A vers\u00e3o de <strong>Tit\u00e2nio<\/strong> apresenta um corpo central de Tit\u00e2nio Lento de Classe 1 com um efeito de <strong>&#8220;p\u00e9rola&#8221;<\/strong> obtido gra\u00e7as a um processo de acabamento especial. \u00c9 a vers\u00e3o perfeita para conseguir <strong>reduzir o peso<\/strong> significativamente.<\/p>\n<p><strong>X-M1 pure Italian style<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>HOMOLOGADO EURO 5. Compat\u00edvel apenas com os alforjes originais<\/p>\n","protected":false},"featured_media":7840,"template":"","meta":{"_acf_changed":false},"product_brand":[22246,22106,22239],"product_cat":[705],"product_tag":[],"class_list":{"0":"post-97728","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2020-f-900-r","7":"product_brand-bmw","8":"product_brand-f-900-r","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/97728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/7840"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=97728"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=97728"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=97728"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=97728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}