{"id":97924,"date":"2026-04-21T14:19:15","date_gmt":"2026-04-21T12:19:15","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/acc-041-a1-ducati-supersport-939-r-2017-2021\/"},"modified":"2026-04-21T14:19:15","modified_gmt":"2026-04-21T12:19:15","slug":"acc-041-a1-ducati-supersport-939-r-2017-2021","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/acc-041-a1-ducati-supersport-939-r-2017-2021\/","title":{"rendered":"ACC.041.A1 &#8211; DUCATI SUPERSPORT 939 \/ R 2017 > 2021"},"content":{"rendered":"<p>Os tubos Dekat de a\u00e7o inoxid\u00e1vel opcionais oferecem uma melhoria de desempenho, particularmente quando utilizados em conjunto com o silenciador mont\u00e1vel da Mivv. Este produto melhora a sua moto com um melhor aspeto e um som \u00fanico. Este produto n\u00e3o est\u00e1 aprovado de acordo com os regulamentos atuais para utiliza\u00e7\u00e3o de motos na estrada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os tubos Dekat de a\u00e7o inoxid\u00e1vel opcionais oferecem uma melhoria de desempenho, particularmente quando utilizados em conjunto com o silenciador mont\u00e1vel da Mivv. Este produto melhora a sua moto com um melhor aspeto e um som \u00fanico. Este produto n\u00e3o est\u00e1 aprovado de acordo com os regulamentos atuais para utiliza\u00e7\u00e3o de motos na estrada.<\/p>\n","protected":false},"featured_media":63272,"template":"","meta":{"_acf_changed":false},"product_brand":[23471,22771,23464],"product_cat":[696],"product_tag":[],"class_list":{"0":"post-97924","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2017-supersport-939-r","7":"product_brand-ducati","8":"product_brand-supersport-939-r","9":"product_cat-catalisador","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/97924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/63272"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=97924"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=97924"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=97924"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=97924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}