{"id":98001,"date":"2026-04-21T14:19:50","date_gmt":"2026-04-21T12:19:50","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/r-du-0005-sm3c-ducati-panigale-v4-2018-2022\/"},"modified":"2026-04-21T14:19:50","modified_gmt":"2026-04-21T12:19:50","slug":"r-du-0005-sm3c-ducati-panigale-v4-2018-2022","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/r-du-0005-sm3c-ducati-panigale-v4-2018-2022\/","title":{"rendered":"R.DU.0005.SM3C \u2013 DUCATI PANIGALE V4 2018 > 2022"},"content":{"rendered":"<p>Gli scarichi completi rappresentano la massima espressione della <strong>tecnologia Mivv<\/strong>. Ogni singolo prodotto \u00e8 testato sui nostri banchi prova prestando particolare attenzione alle prestazioni del motore, al fine di ottenere la massima <strong>performance<\/strong> possibile.<\/p>\n<p>A vers\u00e3o <strong>EVO<\/strong> destinada ao mundo das corridas, \u00e9 a <strong>gama de excel\u00eancia<\/strong> dos escapes completos da Mivv, concebida para responder \u00e0s necessidades das <strong>equipas<\/strong> envolvidas nos v\u00e1rios campeonatos. Desenvolvida tirando partido da experi\u00eancia adquirida no mundo das corridas aos mais altos n\u00edveis, como o <strong>MotoGP<\/strong>, a vers\u00e3o Evo \u00e9 totalmente feita de tit\u00e2nio de classe 1 e os componentes s\u00e3o todos fabricados por soldagem TIG.<\/p>\n<p>Estas s\u00e3o as <strong>vantagens<\/strong> dos nossos escapes completos: <strong>desempenho<\/strong>; m\u00e1ximo; materiais extremamente fi\u00e1veis;<strong>redu\u00e7\u00e3o de peso; facilidade<\/strong> de montagem.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NOT APPROVED It also fits with the standard number plate holder.To improve performance, we recommend remapping the ECU. Map configuration available soon. Sound emissions with db killer:105 db @5500 rpm<\/p>\n","protected":false},"featured_media":9745,"template":"","meta":{"_acf_changed":false},"product_brand":[23394,22771,23387],"product_cat":[21533],"product_tag":[],"class_list":{"0":"post-98001","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2018-panigale-v4","7":"product_brand-ducati","8":"product_brand-panigale-v4","9":"product_cat-evo-sistema-completo","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/98001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/9745"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=98001"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=98001"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=98001"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=98001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}