{"id":99065,"date":"2026-04-21T14:28:29","date_gmt":"2026-04-21T12:28:29","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/m-ho-034-s4c-honda-crf-450-r-2021-2024\/"},"modified":"2026-04-21T14:28:29","modified_gmt":"2026-04-21T12:28:29","slug":"m-ho-034-s4c-honda-crf-450-r-2021-2024","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/m-ho-034-s4c-honda-crf-450-r-2021-2024\/","title":{"rendered":"M.HO.034.S4C &#8211; HONDA CRF 450 R 2021 > 2024"},"content":{"rendered":"<p>Constru\u00eddo com <strong>o melhor layout<\/strong> poss\u00edvel para adaptar-se aos espa\u00e7os dispon\u00edveis na motocicleta, o escape mivv STR-1 foi projetado para garantir o melhor <strong>desempenho, confiabilidade e redu\u00e7\u00e3o de peso<\/strong>.<\/p>\n<p>O escape \u00e9 feito de <strong>Tit\u00e2nio<\/strong> grau 1 e inclui um fundo de carbono de twill 3k e est\u00e1 equipado com um <strong>especial DB-Killer<\/strong> otimizado para <strong>reduzir<\/strong> o ru\u00eddo sem <strong>penalizar<\/strong> o desempenho.<\/p>\n<p>O escape STR-1 foi <strong>projetado<\/strong> para que o motor possa <strong>expressar o melhor<\/strong> de si mesmo <strong>em toda a<\/strong> gama de rota\u00e7\u00f5es do motor. Os <strong>testes de bancada<\/strong> e depois tamb\u00e9m confirmados pelos <strong>testes em pista<\/strong> mostram um <strong>excelente desempenho<\/strong> tanto em <strong>baixas<\/strong> como em <strong>altas velocidades<\/strong>.<\/p>\n<p>O escape STR-1 est\u00e1 equipado com a mais recente gera\u00e7\u00e3o de <strong>fonoabsorventes<\/strong>, desenvolvidos pelo nosso departamento de P&#038;D, e permite que cumpra os <strong>limites de ru\u00eddo<\/strong> cada vez mais rigorosos impostos pelas regulamenta\u00e7\u00f5es nacionais e internacionais para  <strong>competi\u00e7\u00f5es off-road<\/strong>. O material fonoabsorvente \u00e9 <strong>facilmente substitu\u00edvel<\/strong> gra\u00e7as \u00e0 presen\u00e7a <strong>de parafusos<\/strong> localizados na frente do escape que <strong>facilitam<\/strong> esta opera\u00e7\u00e3o.<\/p>\n<p>O escape Mivv STR-1 n\u00e3o requer <strong>remapeamentos<\/strong>. O desenvolvimento foi feito <strong>sem fazer quaisquer altera\u00e7\u00f5es<\/strong> na eletr\u00f3nica. Este \u00e9 <strong>intercambi\u00e1vel<\/strong> com o silenciador de s\u00e9rie.<\/p>\n<p>Este produto s\u00f3 pode ser usado em <strong>pista e em percursos fechados<\/strong>. Foi projetado para adaptar-se a uma motocicleta <strong>equipada de s\u00e9rie<\/strong>, assim como entregue pela empresa-m\u00e3e.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os valores da bancada de teste referem-se \u00e0 configura\u00e7\u00e3o do silenciador + coletor racing. Ru\u00eddo: 114 db<\/p>\n","protected":false},"featured_media":25563,"template":"","meta":{"_acf_changed":false},"product_brand":[24409,24402,23849],"product_cat":[705],"product_tag":[],"class_list":{"0":"post-99065","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2021-crf-450-r","7":"product_brand-crf-450-r","8":"product_brand-honda","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/99065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/25563"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=99065"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=99065"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=99065"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=99065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}