{"id":99128,"date":"2026-04-21T14:28:55","date_gmt":"2026-04-21T12:28:55","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/d-049-sm3c-ducati-hypermotard-950-sp-rve-2021-2024\/"},"modified":"2026-04-21T14:28:55","modified_gmt":"2026-04-21T12:28:55","slug":"d-049-sm3c-ducati-hypermotard-950-sp-rve-2021-2024","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/d-049-sm3c-ducati-hypermotard-950-sp-rve-2021-2024\/","title":{"rendered":"D.049.SM3C \u2013 DUCATI HYPERMOTARD 950 \/ SP\/ RVE 2021 > 2024"},"content":{"rendered":"<p>Concebidos para melhorar a <strong>est\u00e9tica, som e desempenho<\/strong> da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem <strong>distinguir<\/strong> pelo <strong>aspeto<\/strong> das suas motos.<\/p>\n<p>A linha <strong>MK3<\/strong>, resultante da experi\u00eancia adquirida nos campeonatos mundiais de <strong>Moto3 e Moto2<\/strong>, \u00e9 a s\u00edntese perfeita entre <strong>desempenho e tecnologia<\/strong>. Com um <strong>design<\/strong> semelhante aos escapes feitos para <strong>compeonatos mundiais de Moto3<\/strong>, o MK3 \u00e9 um produto <strong>compacto<\/strong>, capaz de libertar o cativante <strong>som da mivv<\/strong>.<\/p>\n<p>A vers\u00e3o de Carbono apresenta um corpo central em <strong>carbono brilhante<\/strong> que, em combina\u00e7\u00e3o com a rede de prote\u00e7\u00e3o na tampa de sa\u00edda, confere ao produto um <strong>aspeto<\/strong> particularmente <strong>de alta tecnologia.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>N\u00c3O APROVADO. Emiss\u00f5es sonoras: 100 db @ 3600 rpm. Para melhorar o desempenho, recomendamos remapear a ECU. Para mais informa\u00e7\u00f5es, leia as informa\u00e7\u00f5es t\u00e9cnicas na caixa da documenta\u00e7\u00e3o.<\/p>\n","protected":false},"featured_media":64181,"template":"","meta":{"_acf_changed":false},"product_brand":[22974,22771,22960],"product_cat":[850],"product_tag":[],"class_list":{"0":"post-99128","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2021-2022-hypermotard-950-sp-rve","7":"product_brand-ducati","8":"product_brand-hypermotard-950-sp-rve","9":"product_cat-2-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/99128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/64181"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=99128"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=99128"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=99128"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=99128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}