{"id":99387,"date":"2026-04-21T14:31:14","date_gmt":"2026-04-21T12:31:14","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/z-001-lxb-zontes-zt-125-u-2021-2024\/"},"modified":"2026-04-21T14:31:14","modified_gmt":"2026-04-21T12:31:14","slug":"z-001-lxb-zontes-zt-125-u-2021-2024","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/pt-pt\/product\/z-001-lxb-zontes-zt-125-u-2021-2024\/","title":{"rendered":"Z.001.LXB \u2013 ZONTES ZT 125 U 2021 > 2024"},"content":{"rendered":"<p>Concebidos para melhorar a <strong>est\u00e9tica, som e desempenho<\/strong> da moto, os Escapes mont\u00e1veis da Mivv s\u00e3o o resultado da m\u00e1xima aten\u00e7\u00e3o ao design, com o objetivo de satisfazer aqueles que se querem <strong>distinguir<\/strong> pelo <strong>aspeto<\/strong> das suas motos.<\/p>\n<p>Fabricado implementando as solu\u00e7\u00f5es t\u00e9cnicas dos modelos da <strong>competi\u00e7\u00e3o<\/strong>, o escape GP \u00e9 um silenciador redondo curto com sa\u00edda ampliada.<\/p>\n<p>Este escape apresenta um corpo central em a\u00e7o inoxid\u00e1vel preto com efeito <strong>&#8220;Black Moon&#8221;<\/strong> escovado, obtido com um processo de colora\u00e7\u00e3o especial que proporciona um aspeto mais <strong>agressivo<\/strong> ao silenciador.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>APROVADO EURO 5 SOMENTE COM O CATALISADOR ACC.042.A1 INSTALADO. N\u00c3O COMPAT\u00cdVEL COM VE\u00cdCULOS EURO 5+ EQUIPADOS COM SENSOR LAMBDA P\u00d3S-CATALISADOR.<\/p>\n","protected":false},"featured_media":62610,"template":"","meta":{"_acf_changed":false},"product_brand":[28751,28805,28754],"product_cat":[19573],"product_tag":[],"class_list":{"0":"post-99387","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2021-zt-125-u","7":"product_brand-zontes","8":"product_brand-zt-125-u","9":"product_cat-planta-completa","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product\/99387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media\/62610"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=99387"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=99387"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=99387"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=99387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}