{"id":1071,"date":"2026-02-03T17:29:35","date_gmt":"2026-02-03T16:29:35","guid":{"rendered":"http:\/\/mivv2026.local\/mivv-%e5%ae%a2%e6%88%b7%e6%9c%8d%e5%8a%a1\/%e5%94%ae%e5%90%8e%e6%94%af%e6%8c%81\/"},"modified":"2026-02-16T17:35:44","modified_gmt":"2026-02-16T16:35:44","slug":"%e5%94%ae%e5%90%8e%e6%94%af%e6%8c%81","status":"publish","type":"page","link":"https:\/\/dev.mivv.com\/zh-hans\/mivv-%e5%ae%a2%e6%88%b7%e6%9c%8d%e5%8a%a1\/%e5%94%ae%e5%90%8e%e6%94%af%e6%8c%81\/","title":{"rendered":"\u552e\u540e\u652f\u6301"},"content":{"rendered":"\n<div class=\"wp-block-columns sezione-faq-assistenza is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:80%\">\n<h2 class=\"wp-block-heading\">\u6280\u672f\u4fe1\u606f<\/h2>\n\n\n\n<p>\u4e0b\u8f7d MIVV \u5b98\u65b9\u300a\u6280\u672f\u4fe1\u606f\u624b\u518c\u300bPDF \u7248\u672c\u3002 \u5305\u542b\u6709\u5173\u8ba4\u8bc1\u3001\u7ef4\u62a4\u548c\u5b89\u5168\u7684\u91cd\u8981\u8bf4\u660e\u3002<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-black-background-color has-text-color has-background has-link-color wp-element-button\" href=\"\/wp-content\/uploads\/2026\/02\/libretto-istruzioni-prodotti-mivv.pdf\" style=\"border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">\u4e0b\u8f7d PDF<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\">\u63d0\u4ea4\u652f\u6301\u8bf7\u6c42<\/h2>\n\n<p>\u8bf7\u586b\u5199\u4e0b\u65b9\u8868\u5355\uff0c\u5e76\u5c3d\u53ef\u80fd\u63d0\u4f9b\u8be6\u7ec6\u4fe1\u606f\u3002 \u56fe\u7247\u5bf9\u4e8e\u6211\u4eec\u7684\u6280\u672f\u4eba\u5458\u51c6\u786e\u5206\u6790\u60a8\u7684\u60c5\u51b5\u81f3\u5173\u91cd\u8981\u3002<\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u8bf7\u786e\u4fdd\u51c6\u5907\u597d\u4ea7\u54c1\u4ee3\u7801\uff0c\u4ee5\u52a0\u5feb\u5904\u7406\u6d41\u7a0b\u3002<\/p>\n<\/blockquote>\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-contact-form-7-contact-form-selector\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f86133-o1\" lang=\"zh-CN\" dir=\"ltr\" data-wpcf7-id=\"86133\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/zh-hans\/wp-json\/wp\/v2\/pages\/1071#wpcf7-f86133-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u7559\u8a00\u8868\u5355\" enctype=\"multipart\/form-data\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"86133\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"zh_CN\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f86133-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"mivv-form-post-vendita\">\n\t<fieldset>\n\t\t<legend>\u5ba2\u6237\u548c\u4ea7\u54c1\u4fe1\u606f\n\t\t<\/legend>\n\t\t<div class=\"mivv-grid-half\">\n\t\t\t<p><label for=\"post-nome\"> \u540d <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"post-first-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" id=\"post-nome\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"\u4f8b\u5982\uff1aMario\" value=\"\" type=\"text\" name=\"post-first-name\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"mivv-grid-half\">\n\t\t\t<p><label for=\"post-cognome\"> \u59d3 <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"post-last-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" id=\"post-cognome\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"\u4f8b\u5982\uff1aRossi\" value=\"\" type=\"text\" name=\"post-last-name\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"mivv-grid-half\">\n\t\t\t<p><label for=\"post-email\"> \u7535\u5b50\u90ae\u7bb1 <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"post-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" id=\"post-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"email@esempio.it\" value=\"\" type=\"email\" name=\"post-email\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"mivv-grid-half\">\n\t\t\t<p><label for=\"post-codice\"> \u4ea7\u54c1\u4ee3\u7801 <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"post-codice\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" id=\"post-codice\" aria-invalid=\"false\" placeholder=\"\u4f8b\u5982\uff1aH.044.LXB\" value=\"\" type=\"text\" name=\"post-codice\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"mivv-grid-full\">\n\t\t\t<p><label for=\"post-tipo\"> \u95ee\u9898\u7c7b\u578b <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"post-tipo\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" id=\"post-tipo\" aria-required=\"true\" aria-invalid=\"false\" name=\"post-tipo\"><option value=\"\">&#8212;\u8bf7\u9009\u62e9&#8212;<\/option><option value=\"\u5b89\u88c5\u56f0\u96be\">\u5b89\u88c5\u56f0\u96be<\/option><option value=\"\u7f3a\u5c11\u90e8\u4ef6\">\u7f3a\u5c11\u90e8\u4ef6<\/option><option value=\"\u5916\u89c2\/\u8d28\u91cf\u95ee\u9898\">\u5916\u89c2\/\u8d28\u91cf\u95ee\u9898<\/option><option value=\"\u8ba4\u8bc1\/\u8bc1\u4e66\">\u8ba4\u8bc1\/\u8bc1\u4e66<\/option><option value=\"\u5176\u4ed6\">\u5176\u4ed6<\/option><\/select><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/fieldset>\n\t<fieldset>\n\t\t<legend>\u95ee\u9898\u8be6\u60c5\n\t\t<\/legend>\n\t\t<div class=\"mivv-grid-full\">\n\t\t\t<p><label for=\"post-messaggio\"> \u8be6\u7ec6\u63cf\u8ff0 <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"post-message\"><textarea cols=\"40\" rows=\"5\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" id=\"post-messaggio\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"\u8bf7\u63cf\u8ff0\u60a8\u9047\u5230\u7684\u95ee\u9898...\" name=\"post-message\"><\/textarea><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"mivv-grid-full\">\n\t\t\t<div class=\"upload-container\">\n\t\t\t\t<p><label class=\"upload-box\" for=\"post-file\"><br \/>\n<span>\u4e0a\u4f20\u95ee\u9898\u7167\u7247\uff08\u6700\u5927 2MB\uff09<\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"post-file\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file\" accept=\".jpg,.jpeg,.png,.pdf\" aria-invalid=\"false\" type=\"file\" name=\"post-file\" \/><\/span><br \/>\n<\/label>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/fieldset>\n\t<div class=\"mivv-form-footer\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"privacy\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"privacy\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">\u6211\u63a5\u53d7\u9690\u79c1\u653f\u7b56<\/span><\/label><\/span><\/span><\/span><br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner btn btn-dark\" type=\"submit\" value=\"\u63d0\u4ea4\u62a5\u544a\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u6280\u672f\u4fe1\u606f \u4e0b\u8f7d MIVV \u5b98\u65b9\u300a\u6280\u672f\u4fe1\u606f\u624b\u518c\u300bPDF \u7248\u672c\u3002 \u5305\u542b\u6709\u5173\u8ba4\u8bc1\u3001\u7ef4\u62a4\u548c\u5b89\u5168\u7684\u91cd\u8981\u8bf4\u660e\u3002 \u63d0\u4ea4\u652f\u6301\u8bf7 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":1032,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1071","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/zh-hans\/wp-json\/wp\/v2\/pages\/1071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/zh-hans\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dev.mivv.com\/zh-hans\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/zh-hans\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/zh-hans\/wp-json\/wp\/v2\/comments?post=1071"}],"version-history":[{"count":1,"href":"https:\/\/dev.mivv.com\/zh-hans\/wp-json\/wp\/v2\/pages\/1071\/revisions"}],"predecessor-version":[{"id":1072,"href":"https:\/\/dev.mivv.com\/zh-hans\/wp-json\/wp\/v2\/pages\/1071\/revisions\/1072"}],"up":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/zh-hans\/wp-json\/wp\/v2\/pages\/1032"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/zh-hans\/wp-json\/wp\/v2\/media?parent=1071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}